{"id":519,"date":"2022-03-22T14:05:08","date_gmt":"2022-03-22T14:05:08","guid":{"rendered":"https:\/\/geiconsultora.com.ar\/business-intelligence\/?page_id=519"},"modified":"2023-12-06T18:18:22","modified_gmt":"2023-12-06T18:18:22","slug":"notas","status":"publish","type":"page","link":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/","title":{"rendered":"Notas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"519\" class=\"elementor elementor-519\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc779b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bc779b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23750a9\" data-id=\"23750a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3100d05 elementor-widget elementor-widget-heading\" data-id=\"3100d05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-528a668 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"528a668\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01dd5c9\" data-id=\"01dd5c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cb1dfc elementor-grid-tablet-3 elementor-grid-3 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient load-more-align-center elementor-widget elementor-widget-posts\" data-id=\"0cb1dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns_tablet&quot;:&quot;3&quot;,&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1450 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/nota-revista-claves-abril-2024\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-1237\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/nota-revista-claves-abril-2024\/\" >\n\t\t\t\tNota Revista Claves Abril 2024\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Hoy entrevistamos a Guillermo Frischling, socio fundador de GEI Consultora, firma que se dedica a acompa\u00f1ar a las PyMes en su camino hacia la profesionalizaci\u00f3n.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/nota-revista-claves-abril-2024\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Nota Revista Claves Abril 2024\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 agosto, 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1449 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/el-peligro-de-la-cultura-excel\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/excel.webp?fit=300%2C169&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-1460\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/excel.webp?w=950&amp;ssl=1 950w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/excel.webp?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/excel.webp?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/el-peligro-de-la-cultura-excel\/\" >\n\t\t\t\tEl peligro de la cultura Excel\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Las hojas de c\u00e1lculo electr\u00f3nicas, como Excel, son fant\u00e1sticas, significaron un antes y un despu\u00e9s en el \u00e1mbito de las empresas, por c\u00f3mo facilitaron la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/el-peligro-de-la-cultura-excel\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre El peligro de la cultura Excel\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 agosto, 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1448 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/la-profesionalizacion-en-nuestras-pymes\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/profesionalizacion.webp?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-1451\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/profesionalizacion.webp?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/profesionalizacion.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/profesionalizacion.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/profesionalizacion.webp?resize=768%2C768&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/la-profesionalizacion-en-nuestras-pymes\/\" >\n\t\t\t\tLa profesionalizaci\u00f3n en nuestras PyMEs\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Cuando uno piensa en PyMEs argentinas, vienen a la mente palabras como intuici\u00f3n, p\u00e1lpito, olfato comercial, habilidad para llevar adelante proyectos en condiciones econ\u00f3micas generales<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/la-profesionalizacion-en-nuestras-pymes\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre La profesionalizaci\u00f3n en nuestras PyMEs\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 agosto, 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1445 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/incorporacion-de-una-herramienta-de-bi\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/d52b5eb1-d1bb-462e-ae6d-7f52931998d2.webp?fit=300%2C226&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-1446\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/d52b5eb1-d1bb-462e-ae6d-7f52931998d2.webp?w=1152&amp;ssl=1 1152w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/d52b5eb1-d1bb-462e-ae6d-7f52931998d2.webp?resize=300%2C226&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/d52b5eb1-d1bb-462e-ae6d-7f52931998d2.webp?resize=1024%2C770&amp;ssl=1 1024w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2024\/08\/d52b5eb1-d1bb-462e-ae6d-7f52931998d2.webp?resize=768%2C577&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/incorporacion-de-una-herramienta-de-bi\/\" >\n\t\t\t\tIncorporaci\u00f3n de una herramienta de BI\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A la hora de evaluar la incorporaci\u00f3n de una herramienta de BI, hay que tener en cuenta unaserie de aspectos comunes dir\u00eda a cualquier decisi\u00f3n<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/incorporacion-de-una-herramienta-de-bi\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Incorporaci\u00f3n de una herramienta de BI\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 agosto, 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1236 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-gestion-empresaria-inteligente\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-1237\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/09\/13del9-Contenido-Propio-Institucional.jpg?resize=768%2C768&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-gestion-empresaria-inteligente\/\" >\n\t\t\t\tGEI:\u00a0GESTION EMPRESARIA INTELIGENTE\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Un empresario Pyme trabaja como un jefe de orquesta.&nbsp; Conoce la m\u00fasica y los instrumentos de su organizaci\u00f3n, pero en esta ardua tarea del d\u00eda<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-gestion-empresaria-inteligente\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre GEI:\u00a0GESTION EMPRESARIA INTELIGENTE\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 septiembre, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1217 post type-post status-publish format-standard has-post-thumbnail hentry category-notas\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-consultora-oportunidad-laboral\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/Logo_GEI_cuadrado.png?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-587\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/Logo_GEI_cuadrado.png?w=710&amp;ssl=1 710w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/Logo_GEI_cuadrado.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/Logo_GEI_cuadrado.png?resize=150%2C150&amp;ssl=1 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-consultora-oportunidad-laboral\/\" >\n\t\t\t\tGEI Consultora- Oportunidad laboral\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>GEI Consultora selecciona: &#x1f4e2; JOVEN PROFESIONAL Para incorporarse a su equipo de consultores. &#x1f449; La b\u00fasqueda se orienta a graduados o pr\u00f3ximos a titularse en<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/gei-consultora-oportunidad-laboral\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre GEI Consultora- Oportunidad laboral\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 agosto, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/pages\/519\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cargar m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-782be36 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"782be36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5225b8\" data-id=\"e5225b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a778327 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"a778327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"http:\/\/geiconsultora.com.ar\/business-intelligence\/contacto\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/pexels-kindel-media-7688336-scaled.jpg?fit=800%2C600&#038;ssl=1);\" role=\"img\" aria-label=\"pexels-kindel-media-7688336\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tContactenos\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tSi desea tener un tablero de control de su negocio para poder tomar decisiones en minutos\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-lg\">\n\t\t\t\t\t\tContactenos ahora\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-ribbon\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\tOportunidad\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contactenos Si desea tener un tablero de control de su negocio para poder tomar decisiones en minutos Contactenos ahora Oportunidad<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-519","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notas - GEI Consultora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notas - GEI Consultora\" \/>\n<meta property=\"og:description\" content=\"Contactenos Si desea tener un tablero de control de su negocio para poder tomar decisiones en minutos Contactenos ahora Oportunidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/\" \/>\n<meta property=\"og:site_name\" content=\"GEI Consultora\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T18:18:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/notas\\\/\",\"url\":\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/notas\\\/\",\"name\":\"Notas - GEI Consultora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#website\"},\"datePublished\":\"2022-03-22T14:05:08+00:00\",\"dateModified\":\"2023-12-06T18:18:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/notas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/notas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/notas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notas\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#website\",\"url\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/\",\"name\":\"GEI Consultora\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#organization\",\"name\":\"GEI Consultora\",\"url\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/geiconsultora.com.ar\\\/business-intelligence\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo_GEI-1.png?fit=710%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/geiconsultora.com.ar\\\/business-intelligence\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo_GEI-1.png?fit=710%2C470&ssl=1\",\"width\":710,\"height\":470,\"caption\":\"GEI Consultora\"},\"image\":{\"@id\":\"http:\\\/\\\/geiconsultora.com.ar\\\/business-intelligence\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notas - GEI Consultora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/","og_locale":"es_ES","og_type":"article","og_title":"Notas - GEI Consultora","og_description":"Contactenos Si desea tener un tablero de control de su negocio para poder tomar decisiones en minutos Contactenos ahora Oportunidad","og_url":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/","og_site_name":"GEI Consultora","article_modified_time":"2023-12-06T18:18:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/","url":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/","name":"Notas - GEI Consultora","isPartOf":{"@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#website"},"datePublished":"2022-03-22T14:05:08+00:00","dateModified":"2023-12-06T18:18:22+00:00","breadcrumb":{"@id":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/geiconsultora.com.ar\/business-intelligence\/notas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/geiconsultora.com.ar\/business-intelligence\/"},{"@type":"ListItem","position":2,"name":"Notas"}]},{"@type":"WebSite","@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#website","url":"http:\/\/geiconsultora.com.ar\/business-intelligence\/","name":"GEI Consultora","description":"","publisher":{"@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/geiconsultora.com.ar\/business-intelligence\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#organization","name":"GEI Consultora","url":"http:\/\/geiconsultora.com.ar\/business-intelligence\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/cropped-Logo_GEI-1.png?fit=710%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/geiconsultora.com.ar\/business-intelligence\/wp-content\/uploads\/2022\/03\/cropped-Logo_GEI-1.png?fit=710%2C470&ssl=1","width":710,"height":470,"caption":"GEI Consultora"},"image":{"@id":"http:\/\/geiconsultora.com.ar\/business-intelligence\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/pages\/519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":2,"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/pages\/519\/revisions"}],"predecessor-version":[{"id":1362,"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/pages\/519\/revisions\/1362"}],"wp:attachment":[{"href":"https:\/\/geiconsultora.com.ar\/business-intelligence\/wp-json\/wp\/v2\/media?parent=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}